{"id":10252,"date":"2017-11-23T11:09:38","date_gmt":"2017-11-23T11:09:38","guid":{"rendered":"http:\/\/localhost\/topline\/?page_id=10252"},"modified":"2017-11-23T11:10:00","modified_gmt":"2017-11-23T11:10:00","slug":"tavolina-mesi","status":"publish","type":"page","link":"https:\/\/topline.al\/en\/dhoma-ndenjes\/tavolina-mesi\/","title":{"rendered":"Tables"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<div id=\"jig1\" class=\"justified-image-grid jig-4853010b4cdd70884419bdd6233757d0 jig-preset-c1\"><div class=\"jig-clearfix\"><\/div><noscript id=\"jig1-html\" class=\"justified-image-grid-html\" data-lazy-src=\"skiplazyload\" data-src=\"skipunveillazyload\"><ul><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/1.jpg\" title=\"1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F1.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"1\" width=\"217\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">1<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/2.png\" title=\"2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F2.png&amp;h=290&amp;q=90&amp;f=.png\" alt=\"2\" width=\"494\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">2<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/3.png\" title=\"3\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F3.png&amp;h=290&amp;q=90&amp;f=.png\" alt=\"3\" width=\"494\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">3<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/4.jpg\" title=\"4\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F4.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"4\" width=\"290\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">4<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/5.png\" title=\"5\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F5.png&amp;h=290&amp;q=90&amp;f=.png\" alt=\"5\" width=\"494\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">5<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/6.jpg\" title=\"6\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F6.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"6\" width=\"239\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">6<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/7.jpg\" title=\"7\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F7.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"7\" width=\"217\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">7<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/8.jpg\" title=\"8\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F8.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"8\" width=\"193\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">8<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/9.png\" title=\"9\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F9.png&amp;h=290&amp;q=90&amp;f=.png\" alt=\"9\" width=\"386\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">9<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/10.jpg\" title=\"10\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F10.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"10\" width=\"414\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">10<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/11.png\" title=\"11\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F11.png&amp;h=290&amp;q=90&amp;f=.png\" alt=\"11\" width=\"193\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">11<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/12.png\" title=\"12\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F12.png&amp;h=290&amp;q=90&amp;f=.png\" alt=\"12\" width=\"193\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">12<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/13.png\" title=\"13\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F13.png&amp;h=290&amp;q=90&amp;f=.png\" alt=\"13\" width=\"386\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">13<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/14.jpg\" title=\"14\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F14.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"14\" width=\"193\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">14<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/15.jpg\" title=\"15\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F15.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"15\" width=\"386\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">15<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/16.jpg\" title=\"16\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F16.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"16\" width=\"193\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">16<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/17.jpg\" title=\"17\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F17.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"17\" width=\"213\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">17<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/18.jpg\" title=\"18\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F18.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"18\" width=\"193\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">18<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/19.jpg\" title=\"19\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F19.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"19\" width=\"290\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">19<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/20.jpg\" title=\"20\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F20.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"20\" width=\"290\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">20<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/21.png\" title=\"21\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F21.png&amp;h=290&amp;q=90&amp;f=.png\" alt=\"21\" width=\"494\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">21<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/23.jpg\" title=\"23\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F23.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"23\" width=\"470\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">23<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/24.jpg\" title=\"24\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F24.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"24\" width=\"470\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">24<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/25.jpg\" title=\"25\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F25.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"25\" width=\"470\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">25<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/26.jpg\" title=\"26\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F26.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"26\" width=\"435\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">26<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/27.jpg\" title=\"27\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F27.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"27\" width=\"435\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">27<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/28.jpg\" title=\"28\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F28.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"28\" width=\"435\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">28<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/29.jpg\" title=\"29\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F29.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"29\" width=\"470\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">29<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/30.jpg\" title=\"30\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F30.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"30\" width=\"470\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">30<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/31.jpg\" title=\"31\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F31.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"31\" width=\"470\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">31<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/32.jpg\" title=\"32\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F32.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"32\" width=\"470\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">32<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/33.jpg\" title=\"33\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F33.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"33\" width=\"470\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">33<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/34.jpg\" title=\"34\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F34.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"34\" width=\"470\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">34<\/p><\/li><li><a href=\"https:\/\/topline.al\/\/wp-content\/gallery\/dhomandenjestavolinamesi\/35.jpg\" title=\"35\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/topline.al\/wp-content\/plugins\/justified-image-grid\/timthumb.php?src=https%3A%2F%2Ftopline.al%2Fwp-content%2Fgallery%2Fdhomandenjestavolinamesi%2F35.jpg&amp;h=290&amp;q=90&amp;f=.jpg\" alt=\"35\" width=\"470\" height=\"290\" \/><\/a><p class=\"jig-HTMLdescription\">35<\/p><\/li><\/ul><\/noscript><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":8784,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-10252","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/topline.al\/en\/wp-json\/wp\/v2\/pages\/10252"}],"collection":[{"href":"https:\/\/topline.al\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/topline.al\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/topline.al\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/topline.al\/en\/wp-json\/wp\/v2\/comments?post=10252"}],"version-history":[{"count":2,"href":"https:\/\/topline.al\/en\/wp-json\/wp\/v2\/pages\/10252\/revisions"}],"predecessor-version":[{"id":10254,"href":"https:\/\/topline.al\/en\/wp-json\/wp\/v2\/pages\/10252\/revisions\/10254"}],"up":[{"embeddable":true,"href":"https:\/\/topline.al\/en\/wp-json\/wp\/v2\/pages\/8784"}],"wp:attachment":[{"href":"https:\/\/topline.al\/en\/wp-json\/wp\/v2\/media?parent=10252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}